{"id":178296,"date":"2023-03-16T12:00:53","date_gmt":"2023-03-16T11:00:53","guid":{"rendered":"https:\/\/newsestlyonnais.fr\/site\/?p=178296"},"modified":"2023-03-16T14:06:06","modified_gmt":"2023-03-16T13:06:06","slug":"cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances","status":"publish","type":"post","link":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/","title":{"rendered":"\u00ab\u00a0Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\u00a0\u00bb"},"content":{"rendered":"<p><strong><span style=\"font-size: 14pt; background-color: #000000; color: #ffffff;\">Pr\u00e9sentation sommaire de chacun<\/span><\/strong><\/p>\n<p><span style=\"color: #ffcc00; background-color: #000000;\">Charlotte Nizet :<\/span> \u00ab 24 ans, vivant sur Lyon, <strong>pr\u00e9paratrice physique<\/strong> \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">K\u00e9vin Charrier :<\/span> \u00ab 25 ans, habitant \u00e0 Villeurbanne, <strong>entraineur en athl\u00e9tisme<\/strong> \u00bb.<\/p>\n<p class=\"Corps\"><span style=\"background-color: #000000; color: #ffcc00;\">Julien Langlet<\/span> : \u00ab 40 ans, je r\u00e9side \u00e0 Villeurbanne, <strong>responsable sportif \u00e0 l\u2019ASVEL Athl\u00e9tisme depuis 2006 <\/strong>\u00bb.<\/p>\n<hr \/>\n<p><strong><span style=\"background-color: #000000; color: #ffffff; font-size: 14pt;\">Votre parcours sportif ?<\/span><\/strong><\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Charlotte :<\/span><\/p>\n<p>\u00ab Etant <strong>passionn\u00e9e par le sport depuis toujours<\/strong>, j\u2019ai pratiqu\u00e9 diverses activit\u00e9s en club et en loisir. J\u2019ai notamment fait 4 ans de GR jusqu\u2019au niveau national. Je me suis vite orient\u00e9e vers la musculation depuis maintenant 7 ans. Je pratique \u00e9galement du cross fit et un peu d\u2019halt\u00e9rophilie qui sont des domaines qui me correspondent et dont je m\u2019inspire dans la construction de mes s\u00e9ances \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">K\u00e9vin :<\/span><\/p>\n<p>\u00ab <strong>Je n\u2019ai pratiqu\u00e9 qu\u2019un seul sport en club, l\u2019athl\u00e9tisme !<\/strong> J\u2019ai d\u00e9but\u00e9 \u00e0 7 ans, dans les cat\u00e9gories d\u2019\u00e9cole d\u2019athl\u00e9tisme, o\u00f9 l\u2019on pratique toutes les disciplines.<br \/>\nA partir de minime, j\u2019ai commenc\u00e9 \u00e0 me sp\u00e9cialiser dans le lancer, d\u2019abord le javelot. Puis je me suis rapidement tourn\u00e9 vers le lancer de poids, que j\u2019ai poursuivi jusqu\u2019en Espoir.<br \/>\nJ\u2019ai ensuite arr\u00eat\u00e9 la pratique de l\u2019athl\u00e9tisme, pour partir \u00e9tudier un an \u00e0 l\u2019\u00e9tranger, sans pour autant oublier l\u2019athl\u00e9tisme \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Julien :<\/span><\/p>\n<p class=\"Corps\">\u00ab <strong>J\u2019ai commenc\u00e9 par le Judo \u00e0 l\u2019\u00e9cole primaire, puis je me suis orient\u00e9 vers l\u2019athl\u00e9tisme en 5e<\/strong>, en suivant un copain qui le pratiquait \u00e0 l\u2019UNSS. J\u2019ai \u00e9t\u00e9 \u00ab rep\u00e9r\u00e9 \u00bb par l\u2019entraineur car je courrais plus vite que son fils, j\u2019ai donc pris ma licence au Beauvais OUC (alias le BOUC) \u00bb.<\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; background-color: #000000; color: #ffffff;\"><strong>D\u00e9finition de votre fonction, ce qui vous plait le plus ?<\/strong><\/span><\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Charlotte :<\/span><\/p>\n<p>\u00ab <strong>Mon r\u00f4le en tant que pr\u00e9paratrice physique est de d\u00e9velopper et maintenir les qualit\u00e9s physiques<\/strong> (force, vitesse puissance, explosivit\u00e9) des athl\u00e8tes, n\u00e9cessaires \u00e0 leur discipline, afin d\u2019am\u00e9liorer leurs capacit\u00e9s physiques et physiologiques pour augmenter leurs performances sportives et \u00eatre dans les meilleures conditions lors des diff\u00e9rentes \u00e9ch\u00e9ances. Cela repose sur une planification, p\u00e9riodisation, programmation r\u00e9fl\u00e9chie. La pr\u00e9paration physique joue un r\u00f4le cl\u00e9 sur la pr\u00e9vention des blessures.<\/p>\n<p>Pour moi mon r\u00f4le ne se r\u00e9sume pas qu\u2019\u00e0 cela. Effectivement <strong>il est important avant tout \u00e0 travers les s\u00e9ances de cr\u00e9er \/ d\u2019avoir une coh\u00e9sion du groupe, une culture de performance<\/strong>, \u00eatre en accord sur \u00ab la culture du club \u00bb. Egalement, je \u00ab co-entraine \u00bb avec Julien et K\u00e9vin les s\u00e9ances sur la technique de sprint. <strong>Nous travaillions tous ensemble et en coh\u00e9sion avec une m\u00eame philosophie de l\u2019entra\u00eenement.<\/strong> Cette collaboration nous permet d\u2019\u00e9changer de partager et de r\u00e9fl\u00e9chir ensemble\u00a0 sur la construction de saison et des s\u00e9ances. une chose rare en athl\u00e9tisme.<\/p>\n<p>Par ailleurs, <strong>je m\u2019occupe de la partie r\u00e9athl\u00e9tisation<\/strong>, cela correspond \u00e0 l\u2019ensemble des moyens non m\u00e9dicaux et non param\u00e9dicaux mis en \u0153uvre pour r\u00e9tablir compl\u00e9tement l\u2019efficacit\u00e9 motrice ou fonctionnelle de l\u2019athl\u00e8te bless\u00e9(e), le tout li\u00e9 \u00e0 la performance sportive. On aborde aussi lors des s\u00e9ances l\u2019aspect r\u00e9cup\u00e9ration (sommeil, alimentation, hydratation.)<\/p>\n<p>Il est difficile de choisir ce qui me plait le plus <strong>dans ce m\u00e9tier tant il est vaste et passionnant<\/strong>. <strong>Je dirais d\u2019aider l\u2019athl\u00e8te \u00e0 s\u2019\u00e9panouir dans ce qu\u2019il fait et de lui donner (une partie) des cl\u00e9s pour y parvenir,<\/strong> de le voir fiers de sa progression, et cerise sur le g\u00e2teau l\u2019accomplissement d\u2019une performance \u00a9 \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">K\u00e9vin :<\/span><\/p>\n<p>\u00ab L\u2019entraineur en athl\u00e9tisme a souvent plusieurs casquettes. Il doit s\u2019occuper de l\u2019entrainement \u00ab technique \u00bb, mais aussi de la partie \u00ab pr\u00e9paration physique \u00bb et du c\u00f4t\u00e9 \u00ab mental \u00bb, ce qui en fait un m\u00e9tier tr\u00e8s complet.<br \/>\n<strong>Mais le m\u00e9tier d\u2019entraineur ne se r\u00e9sume pas qu\u2019\u00e0 la partie \u00e9merg\u00e9e de l\u2019iceberg, les entrainements terrain<\/strong>. En amont, il y a toute la planification \u00e0 effectuer pour que les athl\u00e8tes arrivent au meilleur niveau au moment voulu.<\/p>\n<p><strong>Mais l\u2019athl\u00e9tisme n\u2019est pas que la comp\u00e9tition<\/strong>, il y a notamment les jeunes avec qui le travail est plus bas\u00e9 sur la d\u00e9couverte des disciplines et les apprentissages et d\u00e9veloppement moteur. Un travail diff\u00e9rent mais qui permet d\u2019apprendre beaucoup en tant que jeune entraineur sur la fa\u00e7on de diffuser et transmettre ses connaissances.<\/p>\n<p>De mon c\u00f4t\u00e9 il y a aussi un peu d\u2019administratif, avec entre autre les formations des juges\/entraineurs, le suivi des juges, sans qui il ne pourrait y avoir des comp\u00e9titions.<\/p>\n<p><strong>Ce qui me plait le plus dans le m\u00e9tier d\u2019entraineur est l\u2019accomplissement des athl\u00e8tes, quel que soit leur \u00e2ge et leur niveau<\/strong>. J\u2019ai bien entendu un penchant plus important pour la comp\u00e9tition, qui pour moi caract\u00e9rise l\u2019athl\u00e9tisme. Aider un athl\u00e8te \u00e0 atteindre son meilleur niveau, trouver le petit d\u00e9tail qui peut amener \u00e0 une grande am\u00e9lioration, voir la joie et le bonheur des athl\u00e8tes \u00e0 l\u2019entrainement ou lors de la r\u00e9alisation d\u2019une performance, reste pour moi le plus satisfaisant.<\/p>\n<p><strong>Un deuxi\u00e8me point important qui me plait beaucoup est le travail en \u00e9quipe<\/strong>, qui permet de partager, \u00e9changer, r\u00e9fl\u00e9chir avec des points de vue diff\u00e9rents. <strong>Je pense que ce travail en collaboration nous permet d\u2019\u00eatre plus efficace et d\u2019optimiser le potentiel des athl\u00e8tes !<\/strong> \u00bb<\/p>\n<p><span style=\"color: #ffcc00; background-color: #000000;\">Julien :<\/span><\/p>\n<p class=\"Corps\">\u00ab <strong>Je suis Responsable Sportif de l\u2019ASVEL Athl\u00e9tisme<\/strong> (avec des missions vari\u00e9es telles que : l\u2019organisation de comp\u00e9titions\/cross &#8211; l\u2019entrainement &#8211; organisation des d\u00e9placements\u2026.).<\/p>\n<p class=\"Corps\"><strong>Ce qui me plait le plus dans mes fonctions, c\u2019est la vari\u00e9t\u00e9 des missions<\/strong> et la possibilit\u00e9 d\u2019organiser une partie de mon travail en fonction de mes contraintes familiales \u00bb.<\/p>\n<hr \/>\n<p><span style=\"background-color: #000000; color: #ffffff; font-size: 14pt;\"><strong>Votre formation et \u00e0 quel niveau pouvez-vous exercer ?<\/strong><\/span><\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Charlotte :<\/span><\/p>\n<p>\u00ab J\u2019ai obtenu un DEUST (Dipl\u00f4me d\u2019Etude Universitaire Scientifique et Technique) M\u00e9tiers de la forme \u00e0 l&rsquo;Universit\u00e9 de Lyon 1. Ainsi qu\u2019un DU Ing\u00e9nierie de la Haute Performance Sportive &amp; DATA que j\u2019ai suivi a distance, <strong>c\u2019est lors de cette formation que j\u2019ai commenc\u00e9 \u00e0 travailler avec l\u2019ASVEL, ce qui m\u2019a permis de mettre en optique les connaissances th\u00e9oriques<\/strong> \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">K\u00e9vin :<\/span><\/p>\n<p>\u00ab J\u2019ai suivi un cursus assez classique, en commen\u00e7ant par un Bac Scientifique, que j\u2019ai poursuivi par des \u00e9tudes en STAPS (Fac de sport) pour obtenir une licence Entrainement Sportif, \u00e0 l\u2019universit\u00e9 de Nantes (Loire Atlantique). Ainsi qu\u2019un Master Entrainement Sportif, orient\u00e9 sur la pr\u00e9paration physique, mentale et la r\u00e9athl\u00e9tisation, \u00e0 l\u2019Universit\u00e9 de Lyon 1.<br \/>\nJ\u2019ai \u00e9galement obtenu un DEJEPS (Dipl\u00f4me d\u2019\u00e9tat) mention Athl\u00e9tisme et disciplines associ\u00e9es, au CREPS de Wattignies (Hauts de France), en alternance. <strong>Ces dipl\u00f4mes permettent d\u2019exercer en athl\u00e9tisme, \u00e0 tous les niveaux et dans toutes les cat\u00e9gories d\u2019\u00e2ge<\/strong> \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Julien :<\/span><\/p>\n<p class=\"Corps\">\u00ab J\u2019ai une formation universitaire : Master Entrainement et Management du Sport + le BEES 2\u00b0 Athl\u00e9tisme.<\/p>\n<p class=\"Corps\"><strong>Je pourrais exercer \u00e0 tous les niveaux mais celui qui me plait le plus est de former et travailler avec les jeunes<\/strong> \u00bb.<\/p>\n<hr \/>\n<p><span style=\"background-color: #000000; color: #ffffff; font-size: 14pt;\"><strong>Qu\u2019est-ce que cette activit\u00e9 associative vous a apport\u00e9 dans votre parcours pro ?<\/strong><\/span><\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Charlotte :<\/span><\/p>\n<p>\u00ab Etant dans un m\u00e9tier vaste en perp\u00e9tuelle \u00e9volution, <strong>je continue \u00e0 me former avec des formations et certifications sp\u00e9cialis\u00e9es<\/strong>. Par exemple cette ann\u00e9e, je suis un Mentorat de Fred Marc\u00e9rou sur Coaching Club \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">K\u00e9vin :<\/span><\/p>\n<p>\u00ab Le travail au sein du club permet de mettre en pratique les comp\u00e9tences apprises lors de la formation th\u00e9orique, mais pas seulement. Le travail sur le terrain permet surtout de compl\u00e9ter et d\u00e9velopper ces comp\u00e9tences et surtout d\u2019en acqu\u00e9rir de nouvelles. Car les apprentissages th\u00e9oriques ont beau essayer d\u2019enseigner au mieux, <strong>le meilleur apprentissage se fait sur le terrain<\/strong>. J\u2019ai aussi la chance d\u2019avoir Julien, fort de son exp\u00e9rience, qui permet d\u2019acc\u00e9l\u00e9rer l\u2019apprentissage et qui sait faire face \u00e0 quasiment toutes les situations.<br \/>\n<strong>Une chose importante qu\u2019on retrouve dans peu de structure en athl\u00e9tisme, est le fait de travailler \u00e0 plusieurs, 3 en l\u2019occurrence.<\/strong> Cela permet de se diviser les t\u00e2ches et que chacun mette ses comp\u00e9tences au service des autres. Il suffit d\u2019un peu de coordination, mais pour nous cela s\u2019est fait assez naturellement et n\u2019a jamais pos\u00e9 de probl\u00e8me, bien au contraire !<\/p>\n<p><strong>La pratique est le meilleur moyen d\u2019apprendre et de faire face \u00e0 des situations diverses<\/strong>, qui permettent de s\u2019enrichir personnellement et professionnellement \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Julien :<\/span><\/p>\n<p>\u00ab Depuis 5 ans, je travaille en bin\u00f4me avec Kevin (qui est pass\u00e9 par tous les statuts : Stagiaire &#8211; Apprenti &#8211; Salari\u00e9 \u00e0 temps partiel puis \u00e0 temps plein) et depuis 3 ans, nous avons int\u00e9gr\u00e9 Charlotte \u00e0 notre \u00e9quipe d\u2019encadrement.<\/p>\n<p>Cette association nous permet de nous r\u00e9partir les t\u00e2ches :<\/p>\n<ul>\n<li>Charlotte s\u2019occupe de la partie musculation et r\u00e9-athl\u00e9tisation des athl\u00e8tes<\/li>\n<li>Kevin et moi nous nous occupons de l\u2019aspect technique de toutes les disciplines (hors demi fond et perche) : Kevin est plut\u00f4t sur le sprint et les lancers, je suis pour ma part sur les haies et les sauts (Longueur &#8211; Triple &#8211; Hauteur).<\/li>\n<\/ul>\n<p><strong>Cette association n\u2019est pas fig\u00e9e, en cas de besoin, nous pouvons nous substituer l\u2019un \u00e0 l\u2019autre.<\/strong><\/p>\n<p>Nous nous r\u00e9unissons 2 \u00e0 3 fois par an pour planifier la saison et avant chaque s\u00e9ance nous ajustons les contenus d\u2019entra\u00eenement en fonction des besoins des athl\u00e8tes (douleurs, blessures, fatigues\u2026) \u00bb.<\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt;\"><strong><span style=\"background-color: #000000; color: #ffffff;\">Vos ambitions et anecdotes \u00e9ventuelles ?<\/span><\/strong><\/span><\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Charlotte :<\/span><\/p>\n<p>\u00ab <strong>Mes ambitions sont de d\u00e9velopper d\u2019avantages mes connaissances, gagner en exp\u00e9rience, de m\u2019ouvrir \u00e0 d\u2019autres aspects<\/strong> qui entourent le domaine de la performance sportive, de continuer a \u00e9changer avec d\u2019autres professionnels du m\u00e9tier que ce soit sur l\u2019athl\u00e9tisme ou d\u2019autres disciplines, afin de mettre ce savoir aux services des athl\u00e8tes et de les aider \u00e0 atteindre leurs objectifs fix\u00e9s et le meilleur d\u2019eux-m\u00eames \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">K\u00e9vin :<\/span><\/p>\n<p>\u00ab <strong>Mes ambitions sont de continuer a engranger de l\u2019exp\u00e9rience, amener au plus haut de leur potentiel chacun des athl\u00e8tes et prendre du plaisir<\/strong> dans ce que je fais.<\/p>\n<p><strong>Le c\u00f4t\u00e9 humain de ce travail reste d\u2019une grande richesse et se trouve au c\u0153ur du travail<\/strong>. On a une relation tr\u00e8s importante avec les athl\u00e8tes entrain\u00e9(e)s, qu\u2019il faut savoir g\u00e9rer avec grand soin, notamment chez les plus jeunes. Chaque mot peut avoir son importance (positive comme n\u00e9gative) \u00bb.<\/p>\n<p><span style=\"background-color: #000000; color: #ffcc00;\">Julien :<\/span><\/p>\n<p class=\"Corps\">\u00ab<strong> Cette association porte vraiment ses fruits depuis l\u2019an dernier, o\u00f9 nous avons constat\u00e9 une r\u00e9elle am\u00e9lioration des performances<\/strong> notamment avec le nombre de qualifi\u00e9s aux Championnats de France Jeunes \u00bb.<\/p>\n<hr \/>\n<p><span style=\"font-size: 10pt;\"><span style=\"background-color: #000000; color: #ffffff;\"><strong>Photo \u00e0 la Une <\/strong><\/span>&gt; 3 des membres de l&rsquo;\u00e9quipe d&rsquo;encadrement : Julien Langlet, K\u00e9vin Charrier et Charlotte Nizet.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><span style=\"background-color: #000000;\"><span style=\"color: #ffffff;\">&gt; Toute l&rsquo;ACTU de l&rsquo;ASVEL Athl\u00e9tisme est sur :\u00a0<\/span><\/span><span style=\"color: #ffcc00; background-color: #000000;\"><a style=\"color: #ffcc00; background-color: #000000;\" href=\"https:\/\/www.asvelathle.fr\">https:\/\/www.asvelathle.fr<\/a><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Julien Langlet, Charlotte Nizet et K\u00e9vin Charrier, entraineurs au sein de l&rsquo;ASVEL Athl\u00e9tisme d\u00e9taillent leurs fonctions et avouent appr\u00e9cier particuli\u00e8rement leur collaboration.<\/p>\n","protected":false},"author":4,"featured_media":178379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2968,3421,4286,137,29],"tags":[2221,2162,4661,4663,4619,4662],"class_list":["post-178296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athle-course-pied-marche","category-feminin-actu-au","category-interview-a-la-une","category-interviews","category-villeurbanne","tag-asvel-athle","tag-athletisme","tag-charlotte-nizet","tag-entrainement","tag-julien-langlet","tag-kevin-charrier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances&quot; - News Est Lyonnais<\/title>\n<meta name=\"description\" content=\"&quot;Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances&quot; - News Est Lyonnais\" \/>\n<meta property=\"og:description\" content=\"&quot;Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/\" \/>\n<meta property=\"og:site_name\" content=\"News Est Lyonnais\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-16T11:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-16T13:06:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00e9dac. NEWS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00e9dac. NEWS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/\"},\"author\":{\"name\":\"R\u00e9dac. NEWS\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887\"},\"headline\":\"\u00ab\u00a0Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\u00a0\u00bb\",\"datePublished\":\"2023-03-16T11:00:53+00:00\",\"dateModified\":\"2023-03-16T13:06:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/\"},\"wordCount\":1866,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg\",\"keywords\":[\"ASVEL ATHLE\",\"ATHLETISME\",\"Charlotte Nizet\",\"Entrainement\",\"Julien Langlet\",\"K\u00e9vin Charrier\"],\"articleSection\":[\"Athl\u00e9 | Course pied | Marche\",\"F\u00e9minin (Actu au)\",\"Interview \u00e0 la une\",\"Interviews\",\"Villeurbanne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/\",\"name\":\"\\\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\\\" - News Est Lyonnais\",\"isPartOf\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg\",\"datePublished\":\"2023-03-16T11:00:53+00:00\",\"dateModified\":\"2023-03-16T13:06:06+00:00\",\"description\":\"\\\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg\",\"contentUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg\",\"width\":1200,\"height\":899},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/newsestlyonnais.fr\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#website\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/\",\"name\":\"News Est Lyonnais\",\"description\":\"L&#039;actualit\u00e9 au plus pr\u00e8s\",\"publisher\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsestlyonnais.fr\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\",\"name\":\"News EST LYONNAIS\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"News EST LYONNAIS\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887\",\"name\":\"R\u00e9dac. NEWS\",\"sameAs\":[\"http:\/\/www.newsestlyonnais.fr\",\"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts\",\"https:\/\/fr.linkedin.com\/in\/pascal-oberson-b17045113\"],\"url\":\"https:\/\/newsestlyonnais.fr\/site\/author\/nel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\" - News Est Lyonnais","description":"\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\" - News Est Lyonnais","og_description":"\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\"","og_url":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/","og_site_name":"News Est Lyonnais","article_author":"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts","article_published_time":"2023-03-16T11:00:53+00:00","article_modified_time":"2023-03-16T13:06:06+00:00","og_image":[{"width":1200,"height":899,"url":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg","type":"image\/jpeg"}],"author":"R\u00e9dac. NEWS","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"R\u00e9dac. NEWS","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#article","isPartOf":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/"},"author":{"name":"R\u00e9dac. NEWS","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887"},"headline":"\u00ab\u00a0Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\u00a0\u00bb","datePublished":"2023-03-16T11:00:53+00:00","dateModified":"2023-03-16T13:06:06+00:00","mainEntityOfPage":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/"},"wordCount":1866,"commentCount":0,"publisher":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#organization"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage"},"thumbnailUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg","keywords":["ASVEL ATHLE","ATHLETISME","Charlotte Nizet","Entrainement","Julien Langlet","K\u00e9vin Charrier"],"articleSection":["Athl\u00e9 | Course pied | Marche","F\u00e9minin (Actu au)","Interview \u00e0 la une","Interviews","Villeurbanne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/","url":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/","name":"\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\" - News Est Lyonnais","isPartOf":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage"},"thumbnailUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg","datePublished":"2023-03-16T11:00:53+00:00","dateModified":"2023-03-16T13:06:06+00:00","description":"\"Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\"","breadcrumb":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#primaryimage","url":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg","contentUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2023\/03\/cid_2B64B6DA-557F-48F0-94C2-DA37D7F71822-L0-001.jpg","width":1200,"height":899},{"@type":"BreadcrumbList","@id":"https:\/\/newsestlyonnais.fr\/site\/2023\/03\/16\/cette-association-porte-ses-fruits-depuis-2022-on-a-constate-une-reelle-amelioration-des-performances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/newsestlyonnais.fr\/site\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Cette association porte ses fruits depuis 2022, on a constat\u00e9 une r\u00e9elle am\u00e9lioration des performances\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/newsestlyonnais.fr\/site\/#website","url":"https:\/\/newsestlyonnais.fr\/site\/","name":"News Est Lyonnais","description":"L&#039;actualit\u00e9 au plus pr\u00e8s","publisher":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsestlyonnais.fr\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/newsestlyonnais.fr\/site\/#organization","name":"News EST LYONNAIS","url":"https:\/\/newsestlyonnais.fr\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"News EST LYONNAIS"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887","name":"R\u00e9dac. NEWS","sameAs":["http:\/\/www.newsestlyonnais.fr","https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts","https:\/\/fr.linkedin.com\/in\/pascal-oberson-b17045113"],"url":"https:\/\/newsestlyonnais.fr\/site\/author\/nel\/"}]}},"_links":{"self":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts\/178296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/comments?post=178296"}],"version-history":[{"count":0,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts\/178296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/media\/178379"}],"wp:attachment":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/media?parent=178296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/categories?post=178296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/tags?post=178296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}