{"id":31733,"date":"2017-07-09T18:31:37","date_gmt":"2017-07-09T17:31:37","guid":{"rendered":"http:\/\/newsestlyonnais.fr\/site\/?p=31733"},"modified":"2020-11-05T13:23:49","modified_gmt":"2020-11-05T12:23:49","slug":"meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis","status":"publish","type":"post","link":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/","title":{"rendered":"MEYZIEU | Christelle Dubreuil et Maxime Piout, vainqueurs de l&rsquo;Open de Tennis"},"content":{"rendered":"<h4>Une fois n&rsquo;est pas coutume, c&rsquo;est en matin\u00e9e que l&rsquo;Open de Tennis de Meyzieu qui avait d\u00e9marr\u00e9 le 10 juin dernier a connu ce dimanche son \u00e9pilogue.<\/h4>\n<p>Une \u00e9dition 2017 qui aura connu une nouvelle fois un beau succ\u00e8s avec une forte participation enregistr\u00e9e avec 34 joueuses (22 en seniors &amp; 12 en + 35 ans) et 130 joueurs (94 en seniors &amp; 36 en + 35 ans).<\/p>\n<p>De belles finales disput\u00e9es en deux sets pour les tableaux seniors et qui ont vu Maxime Piout et Christelle Dubreuil s&rsquo;imposer et qui se sont par contre jou\u00e9es en 3 sets (en + de 35 ans) avec des victoires remport\u00e9es par la majolane\u00a0 Sandrine Marzouk et J\u00e9r\u00f4me Dodane.<\/p>\n<p>A noter la pr\u00e9sence, lors de la remise des r\u00e9compenses de Jean Pavarotti, pr\u00e9sident du Comit\u00e9 du Rh\u00f4ne de Tennis et et de G\u00e9rard Revellin, adjoint aux sports de la ville de Meyzieu.<\/p>\n<p><span style=\"text-decoration: underline\">Les r\u00e9sultats de l&rsquo;\u00e9dition 2017<\/span>:<\/p>\n<ul>\n<li><span style=\"text-decoration: underline\"><strong>Seniors Dames<\/strong><\/span>: <strong>Christelle Dubreuil<\/strong> (Tennis Club Mandrinois, 2\/6) bat Jeanne Mariat (TC Fid\u00e9sien, 4\/6) 6\/0,6\/3 . <span style=\"text-decoration: underline\">Demi finalistes<\/span>:\u00a0 Cl\u00e9mence Joly (Lyon Sport M\u00e9tropole, 4\/6) &amp; Laurie Bidault (TC La Pape, 3\/6)<\/li>\n<li><strong><span style=\"text-decoration: underline\">Dames 35 ans<\/span>: Sandrine Marzouk <\/strong>(Meyzieu Tennis, 30) bat Camille Basso (Chassieu Tennis, 30\/1) 6\/3, 3\/6,\u00a0 6\/3.\u00a0\u00a0<span style=\"text-decoration: underline\">Demi finalistes<\/span>: Fran\u00e7oise Bernais (AT Pusignan, 30\/2) &amp; Sylvie Gonzalez (TC Jonage, 30\/3)<\/li>\n<li><strong><span style=\"text-decoration: underline\">Seniors Hommes<\/span>: Maxime Piout <\/strong>(Poinconnet Union Sportive, &#8211; 2\/6) bat Rodrigo Echavarria (Club\u00a0 Etrangers F\u00e9d\u00e9ration, 0)\u00a0 7\/6, 6\/3. <span style=\"text-decoration: underline\">Demi finalistes<\/span>: Alexis Gerra (Chassieu, 1\/6) &amp; S\u00e9bastien Gauvignon (TC St Priest, 3\/6).<strong><br \/>\n<\/strong><\/li>\n<li><strong><span style=\"text-decoration: underline\">Hommes 35 ans<\/span><\/strong>: <strong>J\u00e9r\u00f4me Dodane<\/strong> (AT Pusignan, 15\/1) bat Moussa Amari (TC Charvieu, 15\/1) 3\/6, 6\/4,6\/3. <span style=\"text-decoration: underline\">Demi finalistes<\/span>: Franck Pointet (Lorette Tennis, 15\/4) &amp; Ludovic Boussel (TC St Priest, 15\/4).<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline\"><strong>PHOTO<\/strong> <strong>A LA UNE<\/strong><\/span> : Les finalistes des diff\u00e9rents tableaux.<\/p>\n<div id='gallery-1' class='gallery galleryid-31733 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/newsestlyonnais.fr\/site\/2017\/06\/12\/meyzieu-tennis-actualite-intense-en-cette-mi-juin\/newsestlyonnais-open-meyzieu\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/06\/NEWSESTLYONNAIS-OPEN-MEYZIEU--150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"NEWSESTLYONNAIS - OPEN MEYZIEU\" aria-describedby=\"gallery-1-29077\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-29077'>\n\t\t\t\t    L&rsquo;affiche de cet Open \n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/newsestlyonnais-remise-recompenses-open\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-REMISE-RECOMPENSES-OPEN-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"NEWSESTLYONNAIS - REMISE RECOMPENSES OPEN\" aria-describedby=\"gallery-1-31765\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-31765'>\n\t\t\t\tLa remise des r\u00e9compenses ce dimanche en fin de matin\u00e9e\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/newsestlyonnais-tab-dames-open\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-TAB-DAMES-OPEN-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"NEWSESTLYONNAIS - TAB DAMES OPEN\" aria-describedby=\"gallery-1-31762\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-31762'>\n\t\t\t\tLes finalistes du tableau f\u00e9minin \n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/newsestlyonnais-tab-masc-open\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-TAB-MASC-OPEN-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-31760\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-31760'>\n\t\t\t\tTableau senior, R. Echavarria (finaliste) et  M. Piout (vainqueur) entourent Isabelle Ponsson, juge-arbitre\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/newsestlyonnais-tab-masculin-35-ans\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-TAB-MASCULIN-35-ANS-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"NEWSESTLYONNAIS - TAB MASCULIN 35 ANS\" aria-describedby=\"gallery-1-31764\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-31764'>\n\t\t\t\tTableau masculin 35 ans, \u00e0 gauche J\u00e9r\u00f4me Dodane (vainqueur) et Moussa Amari (finaliste) \n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/newsestlyonnais-vainqu-ta-dames-35-ans\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-VAINQU-TA-DAMES-35-ANS-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-31767\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-31767'>\n\t\t\t\tLa majolane Sandrine Marzouk s&rsquo;est impos\u00e9e dans le tableau + 35 ans \n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une fois n&rsquo;est pas coutume, c&rsquo;est en matin\u00e9e que l&rsquo;Open de Tennis de Meyzieu qui avait d\u00e9marr\u00e9 le 10 juin dernier a connu ce dimanche son \u00e9pilogue. Une \u00e9dition 2017 qui aura connu une nouvelle fois un beau succ\u00e8s avec une forte participation enregistr\u00e9e avec 34 joueuses (22 en seniors &amp; 12 en + 35 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,2992,2991],"tags":[],"class_list":["post-31733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meyzieu","category-tennis-padel","category-tennis-tennis-table-sports"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l&#039;Open de Tennis<\/title>\n<meta name=\"description\" content=\"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l&#039;Open de Tennis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l&#039;Open de Tennis\" \/>\n<meta property=\"og:description\" content=\"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l&#039;Open de Tennis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/\" \/>\n<meta property=\"og:site_name\" content=\"News Est Lyonnais\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-09T17:31:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T12:23:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg?fit=1000%2C750&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00e9dac. NEWS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00e9dac. NEWS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/\"},\"author\":{\"name\":\"R\u00e9dac. NEWS\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887\"},\"headline\":\"MEYZIEU | Christelle Dubreuil et Maxime Piout, vainqueurs de l&rsquo;Open de Tennis\",\"datePublished\":\"2017-07-09T17:31:37+00:00\",\"dateModified\":\"2020-11-05T12:23:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg\",\"articleSection\":[\"Meyzieu\",\"Tennis | Padel\",\"Tennis | Tennis de table\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/\",\"name\":\"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis\",\"isPartOf\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg\",\"datePublished\":\"2017-07-09T17:31:37+00:00\",\"dateModified\":\"2020-11-05T12:23:49+00:00\",\"description\":\"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis\",\"breadcrumb\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg\",\"contentUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg\",\"width\":1000,\"height\":750,\"caption\":\"NEWSESTLYONNAIS FINALISTES OPEN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/newsestlyonnais.fr\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MEYZIEU | Christelle Dubreuil et Maxime Piout, vainqueurs de l&rsquo;Open de Tennis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#website\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/\",\"name\":\"News Est Lyonnais\",\"description\":\"L&#039;actualit\u00e9 au plus pr\u00e8s\",\"publisher\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsestlyonnais.fr\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\",\"name\":\"News EST LYONNAIS\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"News EST LYONNAIS\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887\",\"name\":\"R\u00e9dac. NEWS\",\"sameAs\":[\"http:\/\/www.newsestlyonnais.fr\",\"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts\",\"https:\/\/fr.linkedin.com\/in\/pascal-oberson-b17045113\"],\"url\":\"https:\/\/newsestlyonnais.fr\/site\/author\/nel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis","description":"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/","og_locale":"fr_FR","og_type":"article","og_title":"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis","og_description":"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis","og_url":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/","og_site_name":"News Est Lyonnais","article_author":"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts","article_published_time":"2017-07-09T17:31:37+00:00","article_modified_time":"2020-11-05T12:23:49+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/i1.wp.com\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg?fit=1000%2C750&ssl=1","type":"image\/jpeg"}],"author":"R\u00e9dac. NEWS","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"R\u00e9dac. NEWS","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#article","isPartOf":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/"},"author":{"name":"R\u00e9dac. NEWS","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887"},"headline":"MEYZIEU | Christelle Dubreuil et Maxime Piout, vainqueurs de l&rsquo;Open de Tennis","datePublished":"2017-07-09T17:31:37+00:00","dateModified":"2020-11-05T12:23:49+00:00","mainEntityOfPage":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#organization"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage"},"thumbnailUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg","articleSection":["Meyzieu","Tennis | Padel","Tennis | Tennis de table"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/","url":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/","name":"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis","isPartOf":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage"},"thumbnailUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg","datePublished":"2017-07-09T17:31:37+00:00","dateModified":"2020-11-05T12:23:49+00:00","description":"MEYZIEU : Christelle Dubreuil et Maxime Piout, vainqueurs de l'Open de Tennis","breadcrumb":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#primaryimage","url":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg","contentUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2017\/07\/NEWSESTLYONNAIS-FINALISTES-OPEN.jpg","width":1000,"height":750,"caption":"NEWSESTLYONNAIS FINALISTES OPEN"},{"@type":"BreadcrumbList","@id":"https:\/\/newsestlyonnais.fr\/site\/2017\/07\/09\/meyzieu-christelle-dubreuil-maxime-piout-vainqueurs-de-lopen-de-tennis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/newsestlyonnais.fr\/site\/"},{"@type":"ListItem","position":2,"name":"MEYZIEU | Christelle Dubreuil et Maxime Piout, vainqueurs de l&rsquo;Open de Tennis"}]},{"@type":"WebSite","@id":"https:\/\/newsestlyonnais.fr\/site\/#website","url":"https:\/\/newsestlyonnais.fr\/site\/","name":"News Est Lyonnais","description":"L&#039;actualit\u00e9 au plus pr\u00e8s","publisher":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsestlyonnais.fr\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/newsestlyonnais.fr\/site\/#organization","name":"News EST LYONNAIS","url":"https:\/\/newsestlyonnais.fr\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"News EST LYONNAIS"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887","name":"R\u00e9dac. NEWS","sameAs":["http:\/\/www.newsestlyonnais.fr","https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts","https:\/\/fr.linkedin.com\/in\/pascal-oberson-b17045113"],"url":"https:\/\/newsestlyonnais.fr\/site\/author\/nel\/"}]}},"_links":{"self":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts\/31733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/comments?post=31733"}],"version-history":[{"count":0,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts\/31733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/media\/31735"}],"wp:attachment":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/media?parent=31733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/categories?post=31733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/tags?post=31733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}