{"id":85287,"date":"2019-10-10T06:20:21","date_gmt":"2019-10-10T05:20:21","guid":{"rendered":"http:\/\/newsestlyonnais.fr\/site\/?p=85287"},"modified":"2020-11-02T12:25:06","modified_gmt":"2020-11-02T11:25:06","slug":"rugby-top-14-que-savoir-sur-les-resultats-de-lyon","status":"publish","type":"post","link":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/","title":{"rendered":"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ?"},"content":{"rendered":"<p>Les 14 meilleurs clubs de rugby de France tenteront de remporter le troph\u00e9e cette saison. Au bout de 187 matchs, on saura qui succ\u00e8dera au stade Toulousain, club champion et le plus titr\u00e9 de l\u2019histoire du Rugby fran\u00e7ais.<\/p>\n<p>Le Lyon Olympique Universitaire, deux fois champion de France est \u00e9galement dans cette dynamique de gagner cette saison. Le club a des r\u00e9sultats aussi int\u00e9ressants que <a href=\"https:\/\/www.netbet.fr\/\">netbet.fr<\/a> . En ce d\u00e9but de saison, le LOU Rugby d\u00e9bute fort. Leader au classement avec 26 points, Lyon fait un d\u00e9but de saison impressionnant. Que savoir sur les r\u00e9sultats de Lyon ?<\/p>\n<p>Lyon Olympique Universitaire a fait une saison 2018-2019 assez remarquable. Les joueurs de Lyon ont totalis\u00e9 78 points avec 8 points bonus. Lyon a notamment inscrit 683 points. 525 points ont \u00e9t\u00e9 encaiss\u00e9s par Lyon avec une diff\u00e9rence de 158 points. Lyon a gagn\u00e9 17 matchs pour un match nul et 8 perdus la saison \u00e9coul\u00e9e. L\u2019\u00e9quipe a re\u00e7u en tout 16 cartons jaunes pour z\u00e9ro carton rouge. Lyon a termin\u00e9 \u00e0 la 3\u00b0 place derri\u00e8re le Stade Toulousain et l\u2019ASM Clermont. Mais cette saison, Lyon entend bien se hisser sur le podium et les chiffres en ce d\u00e9but de saison peuvent en t\u00e9moigner.<\/p>\n<h2>Le LOU Rugby, le feu en ce d\u00e9but de saison\u00a0!<\/h2>\n<p>Pour le premier match de la saison, le LOU Rugby a re\u00e7u au Matmut Stadium, le Stade Fran\u00e7ais. Sous la forte chaleur de son public, les locaux ont malmen\u00e9 l\u2019adversaire en s\u2019imposant 43 \u00e0 9. Toujours \u00e0 domicile \u00e0 la deuxi\u00e8me journ\u00e9e, Lyon sort \u00e0 nouveau un grand match. Cette fois-ci, c\u2019est Toulouse qui va subir la d\u00e9faite. Les joueurs de Lyon en feu ont permis \u00e0 l\u2019\u00e9quipe de l&#8217;emporter 22 \u00e0 12. A la troisi\u00e8me journ\u00e9e sur la pelouse de Toulon, Lyon enregistre la troisi\u00e8me victoire de la saison en s\u2019imposant sur un score large de 6 \u00e0 20.<\/p>\n<p>Lyon sur cette m\u00eame lanc\u00e9e inflige une correction \u00e0 Brive lors de la quatri\u00e8me semaine. Alors que le Lou \u00e9voluait \u00e0 domicile, il a corrig\u00e9 l\u2019\u00e9quipe de Brive. Les visiteurs n\u2019ont marqu\u00e9 que trois points alors que Lyon en a marqu\u00e9 59. La cinqui\u00e8me journ\u00e9e a \u00e9t\u00e9 moins fructueuse que les quatre premi\u00e8res mais Lyon s\u2019en sort sur une victoire. Contre le Racing 92 qui \u00e9voluait \u00e0 domicile, Lyon s\u2019est impos\u00e9 20-31. La sixi\u00e8me semaine a \u00e9t\u00e9 la plus serr\u00e9e pour Lyon. Contre la vaillante et athl\u00e9tique \u00e9quipe de Bordeaux-B\u00e8gles, Lyon s\u2019en est sorti in extremis. Score tr\u00e8s \u00e9triqu\u00e9 25 \u00e0 23 avec seulement deux unit\u00e9s de diff\u00e9rence. En 6 journ\u00e9es en Top 14, championnat d&rsquo; \u00e9lite de rugby, Lyon est provisoirement en t\u00eate avec 26 points. Le LOU Rugby rentre progressivement dans la Cour des Grands. Alors que Lyon \u00e9voluait il y a trois ans en division inf\u00e9rieure, le club fait d\u2019\u00e9normes progr\u00e8s. En ce d\u00e9but de championnat ou le Stade Toulousain ne trouve pas encore ses rep\u00e8res, Lyon ne perd pas du temps.<\/p>\n<h2>Le LOU Rugby, qu\u2019est-ce qui fait la force de l\u2019\u00e9quipe\u00a0?<\/h2>\n<p>Le club de rugby fran\u00e7ais, cr\u00e9\u00e9 en 1896 et pr\u00e9sid\u00e9 par Yvan Patet regorge un effectif de jeunes talentueux. Le club a proc\u00e9d\u00e9 \u00e0 de bons recrutements avant le d\u00e9but du championnat et projette r\u00e9aliser un gros coup \u00e0 l\u2019intersaison. L\u2019effectif est constitu\u00e9 \u00e0 l\u2019heure actuelle par des joueurs la plupart fran\u00e7ais. Il s\u2019agit \u00e0 titre d\u2019exemple des arri\u00e8res Jean-Marcellin Buttin et Cl\u00e9ment Laporte. Il y a d\u2019autres joueurs qui \u00e9voluent au poste de Pilier come Vivien Devisme, Raphael Chaume, K\u00e9vin Yameogo, Samir Zouhair et biens d\u2019autres. Il y a \u00e9galement de bons joueurs en troisi\u00e8me ligne comme Patrick Sebola, Julien Puricelli.<\/p>\n<p>Il faut noter que cette nouvelle \u00e9quipe de Lyon est compos\u00e9e de bons joueurs dont quelques-uns form\u00e9s au club. La jeunesse est au rendez-vous et les entraineurs font un travail exceptionnel. Pour l\u2019heure, la saison 2019-2020 est loin d\u2019\u00eatre termin\u00e9e. Mais Lyon prend d\u00e9j\u00e0 une bonne option pour aller loin dans ce tournoi. Les \u00e9quipes habitu\u00e9es au haut de tableau ont mal d\u00e9but\u00e9 la saison. Cela a su profit\u00e9 au LOU Rugby.<\/p>\n<p>Mais ce qu\u2019il ne faut pas perdre de vue, c\u2019est que 20 semaines attendent d\u2019\u00eatre jou\u00e9s au Top 14.<\/p>\n<h1><em><strong>\u00a0\u00a0\u00a0\u00a0 Article r\u00e9dig\u00e9 par Bruno Rossi<\/strong><\/em><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Comme au football, le championnat de France de Rugby a d\u00e9but\u00e9 depuis plusieurs semaines.<\/p>\n","protected":false},"author":4,"featured_media":85290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2996,1625,2999],"tags":[2108,2160],"class_list":["post-85287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football-rugby","category-lyon","category-rugby-a-xv-sports","tag-lou-rugby","tag-rugby-a-xv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ? - News Est Lyonnais<\/title>\n<meta name=\"description\" content=\"Rugby Top 14 : Que savoir sur les r\u00e9sultats de Lyon ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ? - News Est Lyonnais\" \/>\n<meta property=\"og:description\" content=\"Rugby Top 14 : Que savoir sur les r\u00e9sultats de Lyon ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/\" \/>\n<meta property=\"og:site_name\" content=\"News Est Lyonnais\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-10T05:20:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-02T11:25:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg?fit=700%2C394&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00e9dac. NEWS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00e9dac. NEWS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/\"},\"author\":{\"name\":\"R\u00e9dac. NEWS\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887\"},\"headline\":\"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ?\",\"datePublished\":\"2019-10-10T05:20:21+00:00\",\"dateModified\":\"2020-11-02T11:25:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg\",\"keywords\":[\"LOU RUGBY\",\"RUGBY \u00e0 XV\"],\"articleSection\":[\"Foot | Rugby\",\"Lyon\",\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/\",\"name\":\"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ? - News Est Lyonnais\",\"isPartOf\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg\",\"datePublished\":\"2019-10-10T05:20:21+00:00\",\"dateModified\":\"2020-11-02T11:25:06+00:00\",\"description\":\"Rugby Top 14 : Que savoir sur les r\u00e9sultats de Lyon ?\",\"breadcrumb\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg\",\"contentUrl\":\"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/newsestlyonnais.fr\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#website\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/\",\"name\":\"News Est Lyonnais\",\"description\":\"L&#039;actualit\u00e9 au plus pr\u00e8s\",\"publisher\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsestlyonnais.fr\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#organization\",\"name\":\"News EST LYONNAIS\",\"url\":\"https:\/\/newsestlyonnais.fr\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"News EST LYONNAIS\"},\"image\":{\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887\",\"name\":\"R\u00e9dac. NEWS\",\"sameAs\":[\"http:\/\/www.newsestlyonnais.fr\",\"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts\",\"https:\/\/fr.linkedin.com\/in\/pascal-oberson-b17045113\"],\"url\":\"https:\/\/newsestlyonnais.fr\/site\/author\/nel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ? - News Est Lyonnais","description":"Rugby Top 14 : Que savoir sur les r\u00e9sultats de Lyon ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/","og_locale":"fr_FR","og_type":"article","og_title":"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ? - News Est Lyonnais","og_description":"Rugby Top 14 : Que savoir sur les r\u00e9sultats de Lyon ?","og_url":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/","og_site_name":"News Est Lyonnais","article_author":"https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts","article_published_time":"2019-10-10T05:20:21+00:00","article_modified_time":"2020-11-02T11:25:06+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/i1.wp.com\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg?fit=700%2C394&ssl=1","type":"image\/jpeg"}],"author":"R\u00e9dac. NEWS","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"R\u00e9dac. NEWS","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#article","isPartOf":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/"},"author":{"name":"R\u00e9dac. NEWS","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887"},"headline":"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ?","datePublished":"2019-10-10T05:20:21+00:00","dateModified":"2020-11-02T11:25:06+00:00","mainEntityOfPage":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#organization"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage"},"thumbnailUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg","keywords":["LOU RUGBY","RUGBY \u00e0 XV"],"articleSection":["Foot | Rugby","Lyon","Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/","url":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/","name":"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ? - News Est Lyonnais","isPartOf":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage"},"thumbnailUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg","datePublished":"2019-10-10T05:20:21+00:00","dateModified":"2020-11-02T11:25:06+00:00","description":"Rugby Top 14 : Que savoir sur les r\u00e9sultats de Lyon ?","breadcrumb":{"@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#primaryimage","url":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg","contentUrl":"https:\/\/newsestlyonnais.fr\/site\/wp-content\/uploads\/2019\/10\/NEWSESTLYONNAIS-WEB-AG-LOU.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/newsestlyonnais.fr\/site\/2019\/10\/10\/rugby-top-14-que-savoir-sur-les-resultats-de-lyon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/newsestlyonnais.fr\/site\/"},{"@type":"ListItem","position":2,"name":"Rugby Top 14 | Que savoir sur les r\u00e9sultats de Lyon ?"}]},{"@type":"WebSite","@id":"https:\/\/newsestlyonnais.fr\/site\/#website","url":"https:\/\/newsestlyonnais.fr\/site\/","name":"News Est Lyonnais","description":"L&#039;actualit\u00e9 au plus pr\u00e8s","publisher":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsestlyonnais.fr\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/newsestlyonnais.fr\/site\/#organization","name":"News EST LYONNAIS","url":"https:\/\/newsestlyonnais.fr\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"News EST LYONNAIS"},"image":{"@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/newsestlyonnais.fr\/site\/#\/schema\/person\/3230d5615f390bb808365d673001e887","name":"R\u00e9dac. NEWS","sameAs":["http:\/\/www.newsestlyonnais.fr","https:\/\/www.facebook.com\/pascal.oberson.1?fref=ts","https:\/\/fr.linkedin.com\/in\/pascal-oberson-b17045113"],"url":"https:\/\/newsestlyonnais.fr\/site\/author\/nel\/"}]}},"_links":{"self":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts\/85287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/comments?post=85287"}],"version-history":[{"count":0,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/posts\/85287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/media\/85290"}],"wp:attachment":[{"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/media?parent=85287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/categories?post=85287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsestlyonnais.fr\/site\/wp-json\/wp\/v2\/tags?post=85287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}